{"id":2,"name":"Andreas Koller","url":"https:\/\/osam-method.com","description":"Es ist jetzt die Zeit, in welcher wir erkennen k\u00f6nnen, dass die Sch\u00f6pfung einer perfekten Welt f\u00fcr uns selbst, in uns selbst liegt. Ich bin nun seit einer Weile auf diesem Weg, meine eigene perfekte Welt zu kreieren. Dies findet f\u00fcr mich im Innen wie im Aussen statt. \r\nDie Arbeit mit den Quild's hat mir geholfen zu lernen, dass die feinstoffliche Welt unsere physische Welt dominiert. Wir sind in Kontrolle unserer eigenen Welt, wenn wir die Verantwortung daf\u00fcr \u00fcbernehmen und unsere Gedankenwelten sauber halten. Komm mit mir auf den Weg ins Paradies, in Dein Paradies!\r\nIch kreiere mir meine Welt mit jedem gedachten Gedanken. Lass uns also vorsichtig denken!","link":"https:\/\/quild.net\/de\/author\/a-koller\/","slug":"a-koller","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/b86d576300666ad73826174998b27b7333589acb330ef794fa12c7d87eb7269f?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/b86d576300666ad73826174998b27b7333589acb330ef794fa12c7d87eb7269f?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/b86d576300666ad73826174998b27b7333589acb330ef794fa12c7d87eb7269f?s=96&d=mm&r=g"},"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/quild.net\/de\/wp-json\/wp\/v2\/users\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quild.net\/de\/wp-json\/wp\/v2\/users"}]}}